{"id":455026,"date":"2026-07-16T08:18:31","date_gmt":"2026-07-16T11:18:31","guid":{"rendered":"https:\/\/www.ovigilanteonline.com.br\/site\/?p=455026"},"modified":"2026-07-18T07:49:47","modified_gmt":"2026-07-18T10:49:47","slug":"operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/","title":{"rendered":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o"},"content":{"rendered":"<div id=\"ovigi-769928316\" class=\"ovigi-inicio-post-interno ovigi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/onelink.to\/tfjfd3?utm_source=ig&#038;utm_medium=social&#038;utm_content=link_in_bio&#038;fbclid=PAcGRvZgJleHRuA2FlbQIxMQBzcnRjBmFwcF9pZA85MzY2MTk3NDMzOTI0NTkAAacgW20vIuhakYBCxZduUBbwssdSFoAQ7exuq7BFVvR-PR9sdpzVWlAvY7yZog_aem__Bn7V7eJEMspatV_tVfmIA\" target=\"_blank\" aria-label=\"ARTE GIF\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/05\/ARTE-GIF.gif\" alt=\"\"    \/><\/a><\/div>\n<h3 class=\"wp-block-heading\"><strong><em>A\u00e7\u00e3o conjunta do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Militar cumpriu 46 mandados de busca e apreens\u00e3o para combater grupos criminosos armados na regi\u00e3o<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), em atua\u00e7\u00e3o conjunta com a Pol\u00edcia Militar de Minas Gerais (PMMG), deflagrou na manh\u00e3 desta quarta-feira (15) a Opera\u00e7\u00e3o \u00caxodo, voltada ao enfrentamento de grupos criminosos armados com atua\u00e7\u00e3o na Zona da Mata. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o resultou na pris\u00e3o de 26 pessoas, al\u00e9m da apreens\u00e3o de armas, muni\u00e7\u00f5es, drogas e aparelhos celulares. <\/p><div id=\"ovigi-881208545\" class=\"ovigi-conteudo_2-3 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3817182363\" class=\"ovigi-conteudo_2-2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3175715425\" class=\"ovigi-conteudo_2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3691934390\" class=\"ovigi-conteudo_2-4 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a opera\u00e7\u00e3o, foram cumpridos 46 mandados de busca e apreens\u00e3o em endere\u00e7os ligados aos investigados. Do total de presos, 22 foram capturados em cumprimento de mandados de pris\u00e3o. Conforme apurado, um dos mandados de busca e apreens\u00e3o foi cumprido em Leopoldina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As equipes tamb\u00e9m apreenderam uma pistola calibre 9 mm, nove muni\u00e7\u00f5es do mesmo calibre, 40 muni\u00e7\u00f5es calibre .40, 205 buchas de maconha, 113 pinos de coca\u00edna e 14 aparelhos celulares, materiais que ser\u00e3o utilizados para o prosseguimento das investiga\u00e7\u00f5es.<\/p>\n\n\n<div id=\"ovigi-2408898094\">\r\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">continua depois da publicidade<\/p>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.instagram.com\/unimedleopoldina241\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/unimed-materias.jpg\" alt=\"\" class=\"wp-image-455236\"\/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/vest.sudamerica.edu.br\/vest-2026-2\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/sudamerica-materias.jpg\" alt=\"\" class=\"wp-image-453120\"\/><\/a><\/figure>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Segundo a 1\u00aa Promotoria de Justi\u00e7a de Al\u00e9m Para\u00edba, a Opera\u00e7\u00e3o \u00caxodo integra as a\u00e7\u00f5es de enfrentamento ao crime organizado desenvolvidas pelo Minist\u00e9rio P\u00fablico e pela Pol\u00edcia Militar, buscando desarticular grupos criminosos que atuam na regi\u00e3o e contribuir para a preserva\u00e7\u00e3o da ordem p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As investiga\u00e7\u00f5es prosseguem e o material apreendido ser\u00e1 analisado para auxiliar no avan\u00e7o das apura\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Com MPMG<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o conjunta do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Militar cumpriu 46 mandados de busca e apreens\u00e3o para combater grupos criminosos armados na regi\u00e3o O Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), em atua\u00e7\u00e3o conjunta com a Pol\u00edcia Militar de Minas Gerais (PMMG), deflagrou na manh\u00e3 desta quarta-feira (15) a Opera\u00e7\u00e3o \u00caxodo, voltada ao enfrentamento de grupos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":455030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,16,330,26],"tags":[],"class_list":["post-455026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giro-vigilante","category-policia","category-ronda","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"A\u00e7\u00e3o conjunta do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Militar cumpriu 46 mandados de busca e apreens\u00e3o para combater grupos criminosos armados na regi\u00e3o O Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), em atua\u00e7\u00e3o conjunta com a Pol\u00edcia Militar de Minas Gerais (PMMG), deflagrou na manh\u00e3 desta quarta-feira (15) a Opera\u00e7\u00e3o \u00caxodo, voltada ao enfrentamento de grupos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-16T11:18:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-18T10:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornalismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornalismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/\"},\"author\":{\"name\":\"Jornalismo\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"headline\":\"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o\",\"datePublished\":\"2026-07-16T11:18:31+00:00\",\"dateModified\":\"2026-07-18T10:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/\"},\"wordCount\":268,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg\",\"articleSection\":[\"Giro Vigilante\",\"Pol\u00edcia\",\"Ronda Vigilante\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/\",\"name\":\"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg\",\"datePublished\":\"2026-07-16T11:18:31+00:00\",\"dateModified\":\"2026-07-18T10:49:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg\",\"width\":900,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/16\\\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\",\"name\":\"Jornalismo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/","og_locale":"pt_BR","og_type":"article","og_title":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o","og_description":"A\u00e7\u00e3o conjunta do Minist\u00e9rio P\u00fablico e da Pol\u00edcia Militar cumpriu 46 mandados de busca e apreens\u00e3o para combater grupos criminosos armados na regi\u00e3o O Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), em atua\u00e7\u00e3o conjunta com a Pol\u00edcia Militar de Minas Gerais (PMMG), deflagrou na manh\u00e3 desta quarta-feira (15) a Opera\u00e7\u00e3o \u00caxodo, voltada ao enfrentamento de grupos [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2026-07-16T11:18:31+00:00","article_modified_time":"2026-07-18T10:49:47+00:00","og_image":[{"width":900,"height":595,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg","type":"image\/jpeg"}],"author":"Jornalismo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornalismo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/"},"author":{"name":"Jornalismo","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"headline":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o","datePublished":"2026-07-16T11:18:31+00:00","dateModified":"2026-07-18T10:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/"},"wordCount":268,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg","articleSection":["Giro Vigilante","Pol\u00edcia","Ronda Vigilante","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/","name":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg","datePublished":"2026-07-16T11:18:31+00:00","dateModified":"2026-07-18T10:49:47+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-15.32.27.jpeg","width":900,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/16\/operacao-exodo-prende-26-pessoas-e-apreende-armas-drogas-e-municoes-na-regiao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Opera\u00e7\u00e3o \u00caxodo prende 26 pessoas e apreende armas, drogas e muni\u00e7\u00f5es na regi\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6","name":"Jornalismo"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/455026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=455026"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/455026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/455030"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=455026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=455026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=455026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}