{"id":454997,"date":"2026-07-15T07:48:35","date_gmt":"2026-07-15T10:48:35","guid":{"rendered":"https:\/\/www.ovigilanteonline.com.br\/site\/?p=454997"},"modified":"2026-07-18T07:50:03","modified_gmt":"2026-07-18T10:50:03","slug":"homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/","title":{"rendered":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina"},"content":{"rendered":"<div id=\"ovigi-1305729944\" class=\"ovigi-inicio-post-interno ovigi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/onelink.to\/tfjfd3?utm_source=ig&#038;utm_medium=social&#038;utm_content=link_in_bio&#038;fbclid=PAcGRvZgJleHRuA2FlbQIxMQBzcnRjBmFwcF9pZA85MzY2MTk3NDMzOTI0NTkAAacgW20vIuhakYBCxZduUBbwssdSFoAQ7exuq7BFVvR-PR9sdpzVWlAvY7yZog_aem__Bn7V7eJEMspatV_tVfmIA\" target=\"_blank\" aria-label=\"ARTE GIF\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/05\/ARTE-GIF.gif\" alt=\"\"    \/><\/a><\/div>\n<h3 class=\"wp-block-heading\"><em><strong>Ele invadiu estabelecimento no Alto da Ventania e abandonou o equipamento ap\u00f3s ser surpreendido pelo propriet\u00e1rio. Assista ao v\u00eddeo.<\/strong><\/em><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"662\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.27.59.jpeg\" alt=\"\" class=\"wp-image-454999\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.27.59.jpeg 1024w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.27.59-300x194.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.27.59-768x497.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Um homem de 35 anos foi preso na madrugada desta quarta-feira (15) ap\u00f3s tentar furtar um aparelho de ar-condicionado de um estabelecimento comercial no Alto da Ventania, em Leopoldina. A a\u00e7\u00e3o foi registrada por c\u00e2meras de seguran\u00e7a e terminou com a localiza\u00e7\u00e3o do suspeito pela Guarda Civil Municipal (GCM). Veja o v\u00eddeo ao final desta mat\u00e9ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a ocorr\u00eancia, o propriet\u00e1rio do im\u00f3vel, de 71 anos, acompanhou pelo sistema de monitoramento o momento em que um indiv\u00edduo entrou no local pelos fundos, ap\u00f3s romper uma cerca de arame. Em seguida, o indiv\u00edduo retirou um aparelho de ar-condicionado do estabelecimento.<\/p><div id=\"ovigi-139011100\" class=\"ovigi-conteudo_2-3 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3926744759\" class=\"ovigi-conteudo_2-2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-1531571135\" class=\"ovigi-conteudo_2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3928591176\" class=\"ovigi-conteudo_2-4 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ao perceber a invas\u00e3o, o propriet\u00e1rio foi at\u00e9 o im\u00f3vel e gritou com o homem, interrompendo a a\u00e7\u00e3o. O suspeito fugiu e abandonou o aparelho no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equipe da Ronda Ostensiva Municipal (ROMU) foi acionada e, de posse das imagens das c\u00e2meras de seguran\u00e7a, iniciou dilig\u00eancias pela regi\u00e3o. Durante as buscas, os guardas localizaram um homem com caracter\u00edsticas compat\u00edveis com as registradas no v\u00eddeo.<\/p>\n\n\n<div id=\"ovigi-45525976\">\r\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">continua depois da publicidade<\/p>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.instagram.com\/unimedleopoldina241\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/unimed-materias.jpg\" alt=\"\" class=\"wp-image-455236\"\/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/vest.sudamerica.edu.br\/vest-2026-2\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/sudamerica-materias.jpg\" alt=\"\" class=\"wp-image-453120\"\/><\/a><\/figure>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Segundo a Guarda Civil Municipal, durante a abordagem, o homem confessou a tentativa de furto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele recebeu voz de pris\u00e3o e foi encaminhado para a Delegacia de Pol\u00edcia Civil. A ocorr\u00eancia foi encerrada com a pris\u00e3o em flagrante do suspeito.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"324\" style=\"aspect-ratio: 576 \/ 324;\" width=\"576\" controls src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Video-2026-07-15-at-07.28.00-1.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ele invadiu estabelecimento no Alto da Ventania e abandonou o equipamento ap\u00f3s ser surpreendido pelo propriet\u00e1rio. Assista ao v\u00eddeo. Um homem de 35 anos foi preso na madrugada desta quarta-feira (15) ap\u00f3s tentar furtar um aparelho de ar-condicionado de um estabelecimento comercial no Alto da Ventania, em Leopoldina. A a\u00e7\u00e3o foi registrada por c\u00e2meras de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":454998,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,17,11,16,26],"tags":[],"class_list":["post-454997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-geral","category-leopoldina","category-policia","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina\" \/>\n<meta property=\"og:description\" content=\"Ele invadiu estabelecimento no Alto da Ventania e abandonou o equipamento ap\u00f3s ser surpreendido pelo propriet\u00e1rio. Assista ao v\u00eddeo. Um homem de 35 anos foi preso na madrugada desta quarta-feira (15) ap\u00f3s tentar furtar um aparelho de ar-condicionado de um estabelecimento comercial no Alto da Ventania, em Leopoldina. A a\u00e7\u00e3o foi registrada por c\u00e2meras de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T10:48:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-18T10:50:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornalismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornalismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/\"},\"author\":{\"name\":\"Jornalismo\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"headline\":\"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina\",\"datePublished\":\"2026-07-15T10:48:35+00:00\",\"dateModified\":\"2026-07-18T10:50:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/\"},\"wordCount\":266,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/626262.jpg\",\"articleSection\":[\"Cidade\",\"Geral\",\"Leopoldina\",\"Pol\u00edcia\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/\",\"name\":\"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/626262.jpg\",\"datePublished\":\"2026-07-15T10:48:35+00:00\",\"dateModified\":\"2026-07-18T10:50:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/626262.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/626262.jpg\",\"width\":800,\"height\":535},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/15\\\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\",\"name\":\"Jornalismo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/","og_locale":"pt_BR","og_type":"article","og_title":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina","og_description":"Ele invadiu estabelecimento no Alto da Ventania e abandonou o equipamento ap\u00f3s ser surpreendido pelo propriet\u00e1rio. Assista ao v\u00eddeo. Um homem de 35 anos foi preso na madrugada desta quarta-feira (15) ap\u00f3s tentar furtar um aparelho de ar-condicionado de um estabelecimento comercial no Alto da Ventania, em Leopoldina. A a\u00e7\u00e3o foi registrada por c\u00e2meras de [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2026-07-15T10:48:35+00:00","article_modified_time":"2026-07-18T10:50:03+00:00","og_image":[{"width":800,"height":535,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg","type":"image\/jpeg"}],"author":"Jornalismo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornalismo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/"},"author":{"name":"Jornalismo","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"headline":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina","datePublished":"2026-07-15T10:48:35+00:00","dateModified":"2026-07-18T10:50:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/"},"wordCount":266,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg","articleSection":["Cidade","Geral","Leopoldina","Pol\u00edcia","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/","name":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg","datePublished":"2026-07-15T10:48:35+00:00","dateModified":"2026-07-18T10:50:03+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/626262.jpg","width":800,"height":535},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/15\/homem-e-preso-pela-gcm-apos-tentar-furtar-aparelho-de-ar-condicionado-em-leopoldina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Homem \u00e9 preso pela GCM ap\u00f3s tentar furtar aparelho de ar-condicionado em Leopoldina"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6","name":"Jornalismo"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/454997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=454997"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/454997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/454998"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=454997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=454997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=454997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}