{"id":454711,"date":"2026-07-08T16:25:10","date_gmt":"2026-07-08T19:25:10","guid":{"rendered":"https:\/\/www.ovigilanteonline.com.br\/site\/?p=454711"},"modified":"2026-07-10T10:10:10","modified_gmt":"2026-07-10T13:10:10","slug":"nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/","title":{"rendered":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es"},"content":{"rendered":"<div id=\"ovigi-3309511272\" class=\"ovigi-inicio-post-interno ovigi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/onelink.to\/tfjfd3?utm_source=ig&#038;utm_medium=social&#038;utm_content=link_in_bio&#038;fbclid=PAcGRvZgJleHRuA2FlbQIxMQBzcnRjBmFwcF9pZA85MzY2MTk3NDMzOTI0NTkAAacgW20vIuhakYBCxZduUBbwssdSFoAQ7exuq7BFVvR-PR9sdpzVWlAvY7yZog_aem__Bn7V7eJEMspatV_tVfmIA\" target=\"_blank\" aria-label=\"ARTE GIF\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/05\/ARTE-GIF.gif\" alt=\"\"    \/><\/a><\/div>\n<p class=\"wp-block-paragraph\">Centenas de milhares de familiares de pequenos produtores de leite de Minas Gerais podem mudar seu voto, expressando sua frustra\u00e7\u00e3o com promessas do MDA (Pronaf que n\u00e3o funciona) e do pr\u00f3prio Presidente (promessa p\u00fablica de implantar este ano 300 mil embri\u00f5es).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sou entusiasta do Programa de Transfer\u00eancia de Embri\u00f5es para pequenos produtores de leite. S\u00f3 com a melhoria r\u00e1pida e expressiva dos pequenos rebanhos leiteiros os empreendedores rurais tradicionais na atividade leiteira v\u00e3o sobreviver.<\/p><div id=\"ovigi-3968522671\" class=\"ovigi-conteudo_2-3 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-1152714388\" class=\"ovigi-conteudo_2-2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-3603978005\" class=\"ovigi-conteudo_2 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><div id=\"ovigi-1792475621\" class=\"ovigi-conteudo_2-4 ovigi-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4068173061741521\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4068173061741521\" \ndata-ad-slot=\"6460393376\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Muita coisa est\u00e1 errada na tentativa federal de implementar o cr\u00e9dito e a realidade da tecnologia de embri\u00f5es em grande escala em Minas. Come\u00e7a pela nomenclatura. A meta \u00e9 atender PEQUENOS PRODUTORES\u2026 o Minist\u00e9rio encarregado s\u00f3 fala em Produtores Familiares\u2026 Quem n\u00e3o trabalha pelo nome correto pelo produto ou servi\u00e7o est\u00e1 muito, muito distante da realidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na semana pr\u00f3xima sai o novo Plano Safra e o Pronaf. Se n\u00e3o estiver melhor explicitado no MCR (o Manual do Cr\u00e9dito Rural) bye, bye para o Brasil dos pequenos produtores de leite. Mais acentua-se a extin\u00e7\u00e3o de quase 800 mil BRASILEIROS na atividade produtiva de um alimento fundamental. Tenho um certo sentimento de culpa de ter divulgado exaustivamente a disponibilidade do cr\u00e9dito j\u00e1 existente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A frustra\u00e7\u00e3o \u00e9 colossal. Estou muito perto de quem \u00e9 pequeno, de quem produz leite. Nos Munic\u00edpios de Cataguases e Leopoldina onde est\u00e3o sediadas as atividades da minha Fazenda, as Fazendas do Basa, estou doando, com recursos pr\u00f3prios, embri\u00f5es e servi\u00e7os de transfer\u00eancias para TODOS os pequenos produtores que se inscrevam. Estimo atender em 3 anos em torno de 200 produtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falo com eles que me perguntam: chegou ao ponto de precisar o Senhor fazer isso? O Governo n\u00e3o \u00e9 capaz?? N\u00e3o, com tantos bilh\u00f5es no Pronaf em 3 anos e meio o Governo n\u00e3o conseguiu viabilizar NENHUM centavo de cr\u00e9dito para transfer\u00eancia de embri\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Evandro Guimar\u00e3es \u00e9 presidente da Associa\u00e7\u00e3o Brasileira dos Criadores de Gir Leiteiro (ABCGIL); pecuarista, propriet\u00e1rio das Fazendas do Basa.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/image-7.png\" alt=\"\" class=\"wp-image-454713\" style=\"aspect-ratio:1.50295079962083;width:836px;height:auto\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/image-7.png 768w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/image-7-300x200.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n<div id=\"ovigi-452480568\">\r\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">continua depois da publicidade<\/p>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.instagram.com\/unimedleopoldina241\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/unimed-materias.jpg\" alt=\"\" class=\"wp-image-455236\"\/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/vest.sudamerica.edu.br\/vest-2026-2\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/08\/sudamerica-materias.jpg\" alt=\"\" class=\"wp-image-453120\"\/><\/a><\/figure>\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong><br><\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centenas de milhares de familiares de pequenos produtores de leite de Minas Gerais podem mudar seu voto, expressando sua frustra\u00e7\u00e3o com promessas do MDA (Pronaf que n\u00e3o funciona) e do pr\u00f3prio Presidente (promessa p\u00fablica de implantar este ano 300 mil embri\u00f5es). Sou entusiasta do Programa de Transfer\u00eancia de Embri\u00f5es para pequenos produtores de leite. S\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":454715,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,26],"tags":[],"class_list":["post-454711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es\" \/>\n<meta property=\"og:description\" content=\"Centenas de milhares de familiares de pequenos produtores de leite de Minas Gerais podem mudar seu voto, expressando sua frustra\u00e7\u00e3o com promessas do MDA (Pronaf que n\u00e3o funciona) e do pr\u00f3prio Presidente (promessa p\u00fablica de implantar este ano 300 mil embri\u00f5es). Sou entusiasta do Programa de Transfer\u00eancia de Embri\u00f5es para pequenos produtores de leite. S\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-08T19:25:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T13:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1312\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Colunista\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Colunista\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/\"},\"author\":{\"name\":\"Colunista\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/8ad9b7aecc912961c07795d5389c9d7d\"},\"headline\":\"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es\",\"datePublished\":\"2026-07-08T19:25:10+00:00\",\"dateModified\":\"2026-07-10T13:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/\"},\"wordCount\":378,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg\",\"articleSection\":[\"Artigos\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/\",\"name\":\"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg\",\"datePublished\":\"2026-07-08T19:25:10+00:00\",\"dateModified\":\"2026-07-10T13:10:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/8ad9b7aecc912961c07795d5389c9d7d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg\",\"width\":1312,\"height\":811},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/07\\\/08\\\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/8ad9b7aecc912961c07795d5389c9d7d\",\"name\":\"Colunista\",\"sameAs\":[\"https:\\\/\\\/ovigilanteonline.com.br\\\/site\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/","og_locale":"pt_BR","og_type":"article","og_title":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es","og_description":"Centenas de milhares de familiares de pequenos produtores de leite de Minas Gerais podem mudar seu voto, expressando sua frustra\u00e7\u00e3o com promessas do MDA (Pronaf que n\u00e3o funciona) e do pr\u00f3prio Presidente (promessa p\u00fablica de implantar este ano 300 mil embri\u00f5es). Sou entusiasta do Programa de Transfer\u00eancia de Embri\u00f5es para pequenos produtores de leite. S\u00f3 [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2026-07-08T19:25:10+00:00","article_modified_time":"2026-07-10T13:10:10+00:00","og_image":[{"width":1312,"height":811,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg","type":"image\/jpeg"}],"author":"Colunista","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Colunista","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/"},"author":{"name":"Colunista","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/8ad9b7aecc912961c07795d5389c9d7d"},"headline":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es","datePublished":"2026-07-08T19:25:10+00:00","dateModified":"2026-07-10T13:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/"},"wordCount":378,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg","articleSection":["Artigos","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/","name":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg","datePublished":"2026-07-08T19:25:10+00:00","dateModified":"2026-07-10T13:10:10+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/8ad9b7aecc912961c07795d5389c9d7d"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-03-at-13.36.30-1.jpeg","width":1312,"height":811},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/08\/nas-eleicoes-promessas-nao-cumpridas-vazias-cobram-alto-preco-na-hora-do-voto-o-exemplo-da-pecuaria-de-leite-de-pequeno-porte-em-mg-por-evandro-guimaraes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Nas elei\u00e7\u00f5es, promessas n\u00e3o cumpridas, vazias, cobram alto pre\u00e7o na hora do voto. O exemplo da pecu\u00e1ria de leite de pequeno porte em MG | Por Evandro Guimar\u00e3es"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/8ad9b7aecc912961c07795d5389c9d7d","name":"Colunista","sameAs":["https:\/\/ovigilanteonline.com.br\/site\/"]}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/454711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=454711"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/454711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/454715"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=454711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=454711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=454711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}