{"id":449301,"date":"2026-01-17T18:33:41","date_gmt":"2026-01-17T21:33:41","guid":{"rendered":"https:\/\/www.ovigilanteonline.com.br\/site\/?p=449301"},"modified":"2026-01-19T21:47:21","modified_gmt":"2026-01-20T00:47:21","slug":"video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/","title":{"rendered":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong><em>Cavalo surgiu repentinamente na pista durante a madrugada; ocorr\u00eancia foi registrada no km 766 da rodovia, pr\u00f3ximo ao Bairro Popular.<\/em><\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"792\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-17-at-18.22.19.jpeg\" alt=\"\" class=\"wp-image-449304\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-17-at-18.22.19.jpeg 899w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-17-at-18.22.19-300x264.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-17-at-18.22.19-768x677.jpeg 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Um acidente envolvendo um \u00f4nibus de transporte interestadual foi registrado na madrugada deste s\u00e1bado (17), por volta das 2h10, na BR-116, no km 766, em Leopoldina. Veja o v\u00eddeo mais abaixo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ve\u00edculo, pertencente a uma empresa de via\u00e7\u00e3o que seguia no sentido Rio de Janeiro, acabou se envolvendo na ocorr\u00eancia ap\u00f3s um cavalo entrar repentinamente na pista, impossibilitando qualquer manobra de desvio por parte do motorista. Um segundo cavalo tamb\u00e9m foi atingido e os dois morreram no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar do impacto, o condutor conseguiu manter o controle do \u00f4nibus, evitando que o acidente tivesse propor\u00e7\u00f5es maiores. Gra\u00e7as \u00e0 experi\u00eancia e \u00e0 condu\u00e7\u00e3o segura, nenhum passageiro ficou ferido, sendo registrados apenas danos materiais ao ve\u00edculo e ferimentos leves no profissional.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Imagens captadas pelas c\u00e2meras internas do \u00f4nibus mostram o momento exato em que o animal surge \u00e0 frente do ve\u00edculo, evidenciando o risco enfrentado pelo motorista e pelos ocupantes. O v\u00eddeo circulou nas redes sociais e chamou a aten\u00e7\u00e3o para o perigo constante de animais soltos nas rodovias, especialmente durante o per\u00edodo noturno e na madrugada, quando a visibilidade \u00e9 reduzida.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 848 \/ 480;\" width=\"848\" controls src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/acidente-rio-doce-1.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O caso refor\u00e7a o alerta para motoristas que trafegam pela BR-116 e outras rodovias da regi\u00e3o, destacando a import\u00e2ncia da aten\u00e7\u00e3o redobrada, sobretudo em trechos rurais, onde a presen\u00e7a de animais na pista ainda \u00e9 frequente.<\/p>\n\n\n<div id=\"ovigi-1356744964\">\r\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">continua depois da publicidade<\/p>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/unimedleopoldina241\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"\r\nhttps:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/03\/unimedmaterias.jpg\" alt=\"\" class=\"wp-image-428831\"\/><\/a><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.instagram.com\/estancialeopoldina\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" data-id=\"395070\" src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-21-at-15.22.20.jpeg\" alt=\"\" class=\"wp-image-395070\"\/><\/a><\/figure>\r\n<\/figure>\r\n\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\r\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento, n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a identifica\u00e7\u00e3o do propriet\u00e1rio do animal ou sobre eventuais provid\u00eancias administrativas relacionadas ao ocorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Com Aconteceu Virou Not\u00edcia<\/em><\/p>\n\n\n<div  class=\"wp-block-ultimate-post-heading ultp-block-8d557a\"><div class=\"ultp-block-wrapper\"><div class=\"ultp-heading-wrap ultp-heading-style18 ultp-heading-left\"><h2 class=\"ultp-heading-inner\"><span>Leia tamb\u00e9m<\/span><\/h2><\/div><\/div><\/div>\n\n<div  class=\"ultp-post-grid-block wp-block-ultimate-post-post-grid-2 ultp-block-588264 \"><div class=\"ultp-block-wrapper \"><div class=\"ultp-loading\"><div class=\"ultp-loading-blocks\" style=\"width:100%;height:100%;\"><div style=\"left: 0;top: 0;animation-delay:0s;\"><\/div><div style=\"left: 21px;top: 0;animation-delay:0.125s;\"><\/div><div style=\"left: 42px;top: 0;animation-delay:0.25s;\"><\/div><div style=\"left: 0;top: 21px;animation-delay:0.875s;\"><\/div><div style=\"left: 42px;top: 21px;animation-delay:0.375s;\"><\/div><div style=\"left: 0;top: 42px;animation-delay:0.75s;\"><\/div><div style=\"left: 42px;top: 42px;animation-delay:0.625s;\"><\/div><div style=\"left: 21px;top: 42px;animation-delay:0.5s;\"><\/div><\/div><\/div><div class=\"ultp-block-items-wrap ultp-block-row\"><div class=\"ultp-block-item post-id-454961\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/14\/el-nino-se-intensifica-e-tem-81-de-chance-de-ficar-muito-forte-ate-o-fim-do-ano\/\" ><img decoding=\"async\"  alt=\"El Ni\u00f1o se intensifica e tem 81% de chance de ficar muito forte at\u00e9 o fim do ano\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2025\/02\/cidade-tempo-calor-4-870x559.jpg\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/14\/el-nino-se-intensifica-e-tem-81-de-chance-de-ficar-muito-forte-ate-o-fim-do-ano\/\" >El Ni\u00f1o se intensifica e tem 81% de chance de ficar muito forte at\u00e9 o fim do ano<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-454956\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/duas-pessoas-ficam-feridas-em-colisao-no-trevo-de-acesso-a-recreio\/\" ><img decoding=\"async\"  alt=\"Duas pessoas ficam feridas em colis\u00e3o no trevo de acesso a Recreio\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/55154-870x570.jpeg\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/duas-pessoas-ficam-feridas-em-colisao-no-trevo-de-acesso-a-recreio\/\" >Duas pessoas ficam feridas em colis\u00e3o no trevo de acesso a Recreio<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-454953\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/policia-federal-realiza-operacao-em-uba-apos-apreensoes-de-notas-falsas-na-regiao\/\" ><img decoding=\"async\"  alt=\"Pol\u00edcia Federal realiza opera\u00e7\u00e3o em Ub\u00e1 ap\u00f3s apreens\u00f5es de notas falsas na regi\u00e3o\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/image-48-870x570.png\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/policia-federal-realiza-operacao-em-uba-apos-apreensoes-de-notas-falsas-na-regiao\/\" >Pol\u00edcia Federal realiza opera\u00e7\u00e3o em Ub\u00e1 ap\u00f3s apreens\u00f5es de notas falsas na regi\u00e3o<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-454948\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/procon-mpmg-fiscaliza-25-postos-de-combustiveis-e-autua-12-estabelecimentos-na-zona-da-mata\/\" ><img decoding=\"async\"  alt=\"Procon-MPMG fiscaliza 25 postos de combust\u00edveis e autua 12 estabelecimentos na Zona da Mata\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/260710-Postos-Combustiveis-870x570.jpg\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/procon-mpmg-fiscaliza-25-postos-de-combustiveis-e-autua-12-estabelecimentos-na-zona-da-mata\/\" >Procon-MPMG fiscaliza 25 postos de combust\u00edveis e autua 12 estabelecimentos na Zona da Mata<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-454942\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/colisao-frontal-deixa-mulher-morta-e-quatro-feridos-graves-na-br-267-entre-bicas-e-jf\/\" ><img decoding=\"async\"  alt=\"Colis\u00e3o frontal deixa mulher morta e quatro feridos graves na BR-267 entre Bicas e JF\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/656598-870x570.jpeg\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/colisao-frontal-deixa-mulher-morta-e-quatro-feridos-graves-na-br-267-entre-bicas-e-jf\/\" >Colis\u00e3o frontal deixa mulher morta e quatro feridos graves na BR-267 entre Bicas e JF<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"ultp-block-item post-id-454933\"><div class=\"ultp-block-content-wrap ultp-block-content-overlay\"><div class=\"ultp-block-image ultp-block-image-none ultp-block-image-overlay ultp-block-image-simgleGradient\"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/festival-de-viola-de-piacatuba-oferece-oficinas-gratuitas-e-visitas-ao-museu-parque-da-usina-mauricio\/\" ><img decoding=\"async\"  alt=\"Festival de Viola de Piacatuba oferece oficinas gratuitas e visitas ao Museu-Parque da Usina Maur\u00edcio\"  src=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/07\/museu-usina-energisa-piacatuba-870x570.jpg\" \/><\/a><\/div><div class=\"ultp-block-content ultp-block-content-bottomPosition\"><div class=\"ultp-block-content-inner\"><h3 class=\"ultp-block-title \"><a href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/07\/13\/festival-de-viola-de-piacatuba-oferece-oficinas-gratuitas-e-visitas-ao-museu-parque-da-usina-mauricio\/\" >Festival de Viola de Piacatuba oferece oficinas gratuitas e visitas ao Museu-Parque da Usina Maur\u00edcio<\/a><\/h3><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pagination-block-html\" aria-hidden=\"true\" style=\"display: none;\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cavalo surgiu repentinamente na pista durante a madrugada; ocorr\u00eancia foi registrada no km 766 da rodovia, pr\u00f3ximo ao Bairro Popular. Um acidente envolvendo um \u00f4nibus de transporte interestadual foi registrado na madrugada deste s\u00e1bado (17), por volta das 2h10, na BR-116, no km 766, em Leopoldina. Veja o v\u00eddeo mais abaixo. O ve\u00edculo, pertencente a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":449313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,1,11,24,22],"tags":[],"class_list":["post-449301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-destaque","category-leopoldina","category-cultura","category-rodovias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina\" \/>\n<meta property=\"og:description\" content=\"Cavalo surgiu repentinamente na pista durante a madrugada; ocorr\u00eancia foi registrada no km 766 da rodovia, pr\u00f3ximo ao Bairro Popular. Um acidente envolvendo um \u00f4nibus de transporte interestadual foi registrado na madrugada deste s\u00e1bado (17), por volta das 2h10, na BR-116, no km 766, em Leopoldina. Veja o v\u00eddeo mais abaixo. O ve\u00edculo, pertencente a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-17T21:33:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T00:47:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"639\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornalismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornalismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/\"},\"author\":{\"name\":\"Jornalismo\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"headline\":\"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina\",\"datePublished\":\"2026-01-17T21:33:41+00:00\",\"dateModified\":\"2026-01-20T00:47:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/\"},\"wordCount\":302,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/56456.jpg\",\"articleSection\":[\"Cidade\",\"Destaque\",\"Leopoldina\",\"Mais Lidas\",\"Rodovias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/\",\"name\":\"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/56456.jpg\",\"datePublished\":\"2026-01-17T21:33:41+00:00\",\"dateModified\":\"2026-01-20T00:47:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/56456.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/56456.jpg\",\"width\":639,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2026\\\/01\\\/17\\\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\",\"name\":\"Jornalismo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/","og_locale":"pt_BR","og_type":"article","og_title":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina","og_description":"Cavalo surgiu repentinamente na pista durante a madrugada; ocorr\u00eancia foi registrada no km 766 da rodovia, pr\u00f3ximo ao Bairro Popular. Um acidente envolvendo um \u00f4nibus de transporte interestadual foi registrado na madrugada deste s\u00e1bado (17), por volta das 2h10, na BR-116, no km 766, em Leopoldina. Veja o v\u00eddeo mais abaixo. O ve\u00edculo, pertencente a [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2026-01-17T21:33:41+00:00","article_modified_time":"2026-01-20T00:47:21+00:00","og_image":[{"width":639,"height":460,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg","type":"image\/jpeg"}],"author":"Jornalismo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornalismo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/"},"author":{"name":"Jornalismo","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"headline":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina","datePublished":"2026-01-17T21:33:41+00:00","dateModified":"2026-01-20T00:47:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/"},"wordCount":302,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg","articleSection":["Cidade","Destaque","Leopoldina","Mais Lidas","Rodovias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/","name":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg","datePublished":"2026-01-17T21:33:41+00:00","dateModified":"2026-01-20T00:47:21+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2026\/01\/56456.jpg","width":639,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2026\/01\/17\/video-registra-momento-em-que-animal-invade-a-pista-e-e-atropelado-por-onibus-na-br-116-em-leopoldina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeo registra momento em que animal invade a pista e \u00e9 atropelado por \u00f4nibus na BR-116 em Leopoldina"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6","name":"Jornalismo"}]}},"cc_featured_image_caption":{"caption_text":"Aconteceu Virou Not\u00edcia\/Reprodu\u00e7\u00e3o","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/449301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=449301"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/449301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/449313"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=449301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=449301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=449301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}