{"id":435439,"date":"2019-11-17T09:17:00","date_gmt":"2019-11-17T12:17:00","guid":{"rendered":"https:\/\/www.ovigilanteonline.com.br\/site\/?p=435439"},"modified":"2024-08-21T13:19:27","modified_gmt":"2024-08-21T16:19:27","slug":"sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/","title":{"rendered":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ap\u00f3s 27 anos de carreira militar, sargento Fernando da Silva Moreira, natural de Recreio, ingressou na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais. O militar comandava o 2\u00ba Grupamento de Argirita, do 3\u00ba Pelot\u00e3o da 37\u00aa Companhia de Pol\u00edcia Militar de Leopoldina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Filho de Sebasti\u00e3o Moreira e Valta da Silva Moreira, sargento Moreira, casado com M\u00e1rcia e pai de um casal de filhos, Gabriel e Stella, \u00e9 conhecido em Recreio simplesmente como Fernando. Oriundo de uma centen\u00e1ria fam\u00edlia de militares, o sargento menciona a figura de seu bisav\u00f4, o primeiro da fam\u00edlia, a quem Moreira n\u00e3o chegou a conhecer. Depois veio o seu av\u00f4 Alfredo, tamb\u00e9m militar. Seu pai, Sebasti\u00e3o Moreira, era sargento, cujos filhos seguiram a tradi\u00e7\u00e3o. De acordo com a ordem de nascimento: 1\u00ba tenente, Dilson da Silva Moreira; 3\u00ba Jos\u00e9 do Carmo Moreira; 2\u00ba sargento, Alfredo da Silva Moreira; e 3\u00ba sargento, Fernando da Silva Moreira, agora ingressado na Reserva Altiva como 2\u00ba sargento. Atualmente ele mora em Leopoldina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando ingressou na Academia de Pol\u00edcia Militar em dezembro de 1992, em Ub\u00e1. Formou-se soldado em 1993. Trabalhou em Recreio, Ub\u00e1 e Leopoldina. Em 2004 foi promovido a cabo e em 2013 cursou a forma\u00e7\u00e3o de sargentos em Juiz de Fora e foi designado para Argirita, onde atuou at\u00e9 o in\u00edcio de novembro deste ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jornal O Vigilante Online<\/strong><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2019\/11\/0a1c5f95b4374a3d9b710339ddb2f6cd.jpg\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2019\/11\/fernando.jpg\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s 27 anos de carreira militar, sargento Fernando da Silva Moreira, natural de Recreio, ingressou na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais. O militar comandava o 2\u00ba Grupamento de Argirita, do 3\u00ba Pelot\u00e3o da 37\u00aa Companhia de Pol\u00edcia Militar de Leopoldina. Filho de Sebasti\u00e3o Moreira e Valta da Silva Moreira, sargento Moreira, casado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":435440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-435439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s 27 anos de carreira militar, sargento Fernando da Silva Moreira, natural de Recreio, ingressou na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais. O militar comandava o 2\u00ba Grupamento de Argirita, do 3\u00ba Pelot\u00e3o da 37\u00aa Companhia de Pol\u00edcia Militar de Leopoldina. Filho de Sebasti\u00e3o Moreira e Valta da Silva Moreira, sargento Moreira, casado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-17T12:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-21T16:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornalismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornalismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/\"},\"author\":{\"name\":\"Jornalismo\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"headline\":\"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais\",\"datePublished\":\"2019-11-17T12:17:00+00:00\",\"dateModified\":\"2024-08-21T16:19:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/\"},\"wordCount\":237,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fernando.jpg\",\"articleSection\":[\"Destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/\",\"name\":\"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fernando.jpg\",\"datePublished\":\"2019-11-17T12:17:00+00:00\",\"dateModified\":\"2024-08-21T16:19:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fernando.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fernando.jpg\",\"width\":745,\"height\":541},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2019\\\/11\\\/17\\\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/538fdfb33c0c411cd14a732e7cf14aa6\",\"name\":\"Jornalismo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/","og_locale":"pt_BR","og_type":"article","og_title":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais","og_description":"Ap\u00f3s 27 anos de carreira militar, sargento Fernando da Silva Moreira, natural de Recreio, ingressou na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais. O militar comandava o 2\u00ba Grupamento de Argirita, do 3\u00ba Pelot\u00e3o da 37\u00aa Companhia de Pol\u00edcia Militar de Leopoldina. Filho de Sebasti\u00e3o Moreira e Valta da Silva Moreira, sargento Moreira, casado [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2019-11-17T12:17:00+00:00","article_modified_time":"2024-08-21T16:19:27+00:00","og_image":[{"width":745,"height":541,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg","type":"image\/jpeg"}],"author":"Jornalismo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jornalismo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/"},"author":{"name":"Jornalismo","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"headline":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais","datePublished":"2019-11-17T12:17:00+00:00","dateModified":"2024-08-21T16:19:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/"},"wordCount":237,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg","articleSection":["Destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/","name":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg","datePublished":"2019-11-17T12:17:00+00:00","dateModified":"2024-08-21T16:19:27+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2024\/08\/fernando.jpg","width":745,"height":541},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2019\/11\/17\/sargento-moreira-ingressa-na-reserva-altiva-da-policia-militar-de-minas-gerais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sargento Moreira ingressa na Reserva Altiva da Pol\u00edcia Militar de Minas Gerais"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/538fdfb33c0c411cd14a732e7cf14aa6","name":"Jornalismo"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/435439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=435439"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/435439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/435440"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=435439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=435439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=435439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}