{"id":395452,"date":"2021-11-27T19:37:45","date_gmt":"2021-11-27T22:37:45","guid":{"rendered":"https:\/\/ovigilanteonline.com.br\/site\/?p=395452"},"modified":"2021-11-27T19:39:37","modified_gmt":"2021-11-27T22:39:37","slug":"nova-feira-do-artesao-e-inaugurada-em-leopoldina","status":"publish","type":"post","link":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/","title":{"rendered":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"904\" height=\"680\" src=\"https:\/\/ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-27-at-19.13.00.jpeg\" alt=\"\" class=\"wp-image-395459\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-27-at-19.13.00.jpeg 904w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-27-at-19.13.00-300x226.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-27-at-19.13.00-600x451.jpeg 600w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-27-at-19.13.00-768x578.jpeg 768w\" sizes=\"auto, (max-width: 904px) 100vw, 904px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"552\" src=\"https:\/\/ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-3.jpeg\" alt=\"\" class=\"wp-image-395453\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-3.jpeg 900w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-3-600x368.jpeg 600w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-3-300x184.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-3-768x471.jpeg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Prefeitura de Leopoldina inaugurou, na manh\u00e3 deste s\u00e1bado, dia 27 de novembro, a Nova Feira do Artes\u00e3o, na Pra\u00e7a F\u00e9lix Martins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo formato da tradicional &#8220;feirinha&#8221; conta com barraquinhas padronizadas, feirantes cadastrados e regularizados com MEI e m\u00fasica ao vivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Nova Feira do Artes\u00e3o acontecer\u00e1 todos os s\u00e1bados, na Pra\u00e7a F\u00e9lix Martins, de 8h00 \u00e0s 14h00 e contar\u00e1 com m\u00fasica ao vivo. Hoje, o repert\u00f3rio foi comandado pelo m\u00fasico Saulo Lima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme informou a prefeitura, o objetivo deste novo formato \u00e9 valorizar os feirantes e garantir um ambiente mais acolhedor para os leopoldinenses.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"551\" src=\"https:\/\/ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-4.jpeg\" alt=\"\" class=\"wp-image-395454\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-4.jpeg 900w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-4-600x367.jpeg 600w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-4-300x184.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-4-768x470.jpeg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"603\" src=\"https:\/\/ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-5.jpeg\" alt=\"\" class=\"wp-image-395455\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-5.jpeg 900w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-5-600x402.jpeg 600w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-5-300x201.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-5-768x515.jpeg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"677\" src=\"https:\/\/ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-.jpeg\" alt=\"\" class=\"wp-image-395458\" srcset=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-.jpeg 900w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO--300x226.jpeg 300w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO--600x451.jpeg 600w, https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO--768x578.jpeg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Fonte e fotos: Prefeitura de Leopoldina<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Leopoldina inaugurou, na manh\u00e3 deste s\u00e1bado, dia 27 de novembro, a Nova Feira do Artes\u00e3o, na Pra\u00e7a F\u00e9lix Martins. O novo formato da tradicional &#8220;feirinha&#8221; conta com barraquinhas padronizadas, feirantes cadastrados e regularizados com MEI e m\u00fasica ao vivo. A Nova Feira do Artes\u00e3o acontecer\u00e1 todos os s\u00e1bados, na Pra\u00e7a F\u00e9lix Martins, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":395456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-395452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Leopoldina inaugurou, na manh\u00e3 deste s\u00e1bado, dia 27 de novembro, a Nova Feira do Artes\u00e3o, na Pra\u00e7a F\u00e9lix Martins. O novo formato da tradicional &#8220;feirinha&#8221; conta com barraquinhas padronizadas, feirantes cadastrados e regularizados com MEI e m\u00fasica ao vivo. A Nova Feira do Artes\u00e3o acontecer\u00e1 todos os s\u00e1bados, na Pra\u00e7a F\u00e9lix Martins, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/\" \/>\n<meta property=\"og:site_name\" content=\"O VIGILANTE ONLINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovigilanteonline\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-27T22:37:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-27T22:39:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00falio Cabral\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00falio Cabral\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/\"},\"author\":{\"name\":\"J\u00falio Cabral\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a58c0d2b43f23d108fa2b3c67db4e4df\"},\"headline\":\"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina\",\"datePublished\":\"2021-11-27T22:37:45+00:00\",\"dateModified\":\"2021-11-27T22:39:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/\"},\"wordCount\":120,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FEIRA-ARTESANATO-6.jpeg\",\"articleSection\":[\"Destaque\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/\",\"name\":\"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FEIRA-ARTESANATO-6.jpeg\",\"datePublished\":\"2021-11-27T22:37:45+00:00\",\"dateModified\":\"2021-11-27T22:39:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a58c0d2b43f23d108fa2b3c67db4e4df\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FEIRA-ARTESANATO-6.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/FEIRA-ARTESANATO-6.jpeg\",\"width\":900,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/2021\\\/11\\\/27\\\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/\",\"name\":\"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ovigilanteonline.com.br\\\/site\\\/#\\\/schema\\\/person\\\/a58c0d2b43f23d108fa2b3c67db4e4df\",\"name\":\"J\u00falio Cabral\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/","og_locale":"pt_BR","og_type":"article","og_title":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina","og_description":"A Prefeitura de Leopoldina inaugurou, na manh\u00e3 deste s\u00e1bado, dia 27 de novembro, a Nova Feira do Artes\u00e3o, na Pra\u00e7a F\u00e9lix Martins. O novo formato da tradicional &#8220;feirinha&#8221; conta com barraquinhas padronizadas, feirantes cadastrados e regularizados com MEI e m\u00fasica ao vivo. A Nova Feira do Artes\u00e3o acontecer\u00e1 todos os s\u00e1bados, na Pra\u00e7a F\u00e9lix Martins, [&hellip;]","og_url":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/","og_site_name":"O VIGILANTE ONLINE","article_publisher":"https:\/\/www.facebook.com\/ovigilanteonline","article_published_time":"2021-11-27T22:37:45+00:00","article_modified_time":"2021-11-27T22:39:37+00:00","og_image":[{"width":900,"height":549,"url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg","type":"image\/jpeg"}],"author":"J\u00falio Cabral","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"J\u00falio Cabral","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#article","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/"},"author":{"name":"J\u00falio Cabral","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/a58c0d2b43f23d108fa2b3c67db4e4df"},"headline":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina","datePublished":"2021-11-27T22:37:45+00:00","dateModified":"2021-11-27T22:39:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/"},"wordCount":120,"commentCount":0,"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg","articleSection":["Destaque","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/","url":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/","name":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina","isPartOf":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#primaryimage"},"image":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg","datePublished":"2021-11-27T22:37:45+00:00","dateModified":"2021-11-27T22:39:37+00:00","author":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/a58c0d2b43f23d108fa2b3c67db4e4df"},"breadcrumb":{"@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#primaryimage","url":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg","contentUrl":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-content\/uploads\/2021\/11\/FEIRA-ARTESANATO-6.jpeg","width":900,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/2021\/11\/27\/nova-feira-do-artesao-e-inaugurada-em-leopoldina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ovigilanteonline.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Nova Feira do Artes\u00e3o \u00e9 inaugurada em Leopoldina"}]},{"@type":"WebSite","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#website","url":"https:\/\/www.ovigilanteonline.com.br\/site\/","name":"O VIGILANTE ONLINE - Not\u00edcias de Leopoldina e regi\u00e3o","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ovigilanteonline.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.ovigilanteonline.com.br\/site\/#\/schema\/person\/a58c0d2b43f23d108fa2b3c67db4e4df","name":"J\u00falio Cabral"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/395452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=395452"}],"version-history":[{"count":0,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/posts\/395452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media\/395456"}],"wp:attachment":[{"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=395452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=395452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ovigilanteonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=395452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}